{"id":12985,"date":"2016-05-04T14:25:53","date_gmt":"2016-05-04T12:25:53","guid":{"rendered":"http:\/\/vegapas.com\/contacto\/"},"modified":"2017-02-21T11:40:33","modified_gmt":"2017-02-21T10:40:33","slug":"contatto","status":"publish","type":"page","link":"https:\/\/vegapas.com\/it\/contatto\/","title":{"rendered":"Contatto"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; gap=&#8221;30&#8243; css=&#8221;.vc_custom_1484739459996{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 30px !important;padding-bottom: 30px !important;background-color: #0084cf !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1487673180106{margin-bottom: 12px !important;}&#8221;]<\/p>\n<h6 style=\"color: #ffffff; text-align: center; opacity: 0.7;\">Telefono:<\/h6>\n<p>[\/vc_column_text][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #ffffff !important; text-align: center; text-decoration: none;\"><a style=\"color: #ffffff !important; text-align: center; text-decoration: none;\" href=\"#\">+34 942 559 841<\/a><\/h4>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1484811173131{margin-bottom: 12px !important;}&#8221;]<\/p>\n<h6 style=\"color: #ffffff; text-align: center; opacity: 0.7;\">Fax:<\/h6>\n<p>[\/vc_column_text][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h4 style=\"color: #ffffff !important; text-align: center; text-decoration: none;\"><a style=\"color: #ffffff !important; text-align: center; text-decoration: none;\" href=\"#\">0034 942 565132<\/a><\/h4>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1468751410004{margin-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1470052060178{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221; offset=&#8221;vc_col-md-6&#8243;]<div id='wrap_map_6a048d9587e90' class='ultimate-map-wrapper ult-adjust-bottom-margin ' style='margin:0px; height:900px;'><div id='map_6a048d9587e90' data-map_override='0' class='ultimate_google_map wpb_content_element ' style='width:100%;height:900px;'><\/div><\/div><script type='text\/javascript'>\r\n\t\t\t(function($) {\r\n  \t\t\t'use strict';\r\n\t\t\tvar map_map_6a048d9587e90 = null;\r\n\t\t\tvar coordinate_map_6a048d9587e90;\r\n\t\t\tvar isDraggable = $(document).width() > 641 ? true : true;\r\n\t\t\ttry\r\n\t\t\t{\r\n\t\t\t\tvar map_map_6a048d9587e90 = null;\r\n\t\t\t\tvar coordinate_map_6a048d9587e90;\r\n\t\t\t\tcoordinate_map_6a048d9587e90=new google.maps.LatLng(43.396281, -3.848445);\r\n\t\t\t\tvar mapOptions=\r\n\t\t\t\t{\r\n\t\t\t\t\tzoom: 13,\r\n\t\t\t\t\tcenter: coordinate_map_6a048d9587e90,\r\n\t\t\t\t\tscaleControl: true,\r\n\t\t\t\t\tstreetViewControl: false,\r\n\t\t\t\t\tmapTypeControl: true,\r\n\t\t\t\t\tpanControl: false,\r\n\t\t\t\t\tzoomControl: true,\r\n\t\t\t\t\tscrollwheel: false,\r\n\t\t\t\t\tdraggable: isDraggable,\r\n\t\t\t\t\tzoomControlOptions: {\r\n\t\t\t\t\t  style: google.maps.ZoomControlStyle.SMALL\r\n\t\t\t\t\t}, mapTypeControlOptions: {\r\n\t\t\t\t\t  \t\tmapTypeIds: [google.maps.MapTypeId.ROADMAP, 'map_style']\r\n\t\t\t\t\t\t}};var styles = [\n    {\n        \"featureType\": \"water\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#e9e9e9\"\n            },\n            {\n                \"lightness\": 17\n            }\n        ]\n    },\n    {\n        \"featureType\": \"landscape\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#f5f5f5\"\n            },\n            {\n                \"lightness\": 20\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            },\n            {\n                \"lightness\": 17\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"geometry.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            },\n            {\n                \"lightness\": 29\n            },\n            {\n                \"weight\": 0.2\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.arterial\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            },\n            {\n                \"lightness\": 18\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.local\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            },\n            {\n                \"lightness\": 16\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#f5f5f5\"\n            },\n            {\n                \"lightness\": 21\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi.park\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#dedede\"\n            },\n            {\n                \"lightness\": 21\n            }\n        ]\n    },\n    {\n        \"elementType\": \"labels.text.stroke\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            },\n            {\n                \"color\": \"#ffffff\"\n            },\n            {\n                \"lightness\": 16\n            }\n        ]\n    },\n    {\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"saturation\": 36\n            },\n            {\n                \"color\": \"#333333\"\n            },\n            {\n                \"lightness\": 40\n            }\n        ]\n    },\n    {\n        \"elementType\": \"labels.icon\",\n        \"stylers\": [\n            {\n                \"visibility\": \"off\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"transit\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#f2f2f2\"\n            },\n            {\n                \"lightness\": 19\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#fefefe\"\n            },\n            {\n                \"lightness\": 20\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative\",\n        \"elementType\": \"geometry.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#fefefe\"\n            },\n            {\n                \"lightness\": 17\n            },\n            {\n                \"weight\": 1.2\n            }\n        ]\n    }\n];\r\n\t\t\t\t\t\tvar styledMap = new google.maps.StyledMapType(styles,\r\n\t\t\t\t\t    \t{name: \"Styled Map\"});var map_map_6a048d9587e90 = new google.maps.Map(document.getElementById('map_6a048d9587e90'),mapOptions);map_map_6a048d9587e90.mapTypes.set('map_style', styledMap);\r\n \t\t\t\t\t\t\t map_map_6a048d9587e90.setMapTypeId('map_style');\r\n\t\t\t\t\t\tvar x = 'infowindow_open_value';\r\n\t\t\t\t\t\tvar marker_map_6a048d9587e90 = new google.maps.Marker({\r\n\t\t\t\t\t\tposition: new google.maps.LatLng(43.396281, -3.848445),\r\n\t\t\t\t\t\tanimation:  google.maps.Animation.DROP,\r\n\t\t\t\t\t\tmap: map_map_6a048d9587e90,\r\n\t\t\t\t\t\ticon: 'https:\/\/vegapas.com\/wp-content\/uploads\/2016\/05\/vegapas_mark_2.png'\r\n\t\t\t\t\t});\r\n\t\t\t\t\tgoogle.maps.event.addListener(marker_map_6a048d9587e90, 'click', toggleBounce);var infowindow = new google.maps.InfoWindow();\r\n\t\t\t\t\t\t\tinfowindow.setContent('<div class=\"map_info_text\" style=\\'color:#000;\\'>Pol\u00edgono Industrial de Guarnizo, Parcela 94<br \/> 39611, Astillero.\u00a0Cantabria<\/div>');google.maps.event.addListener(marker_map_6a048d9587e90, 'click', function() {\r\n\t\t\t\t\t\t\t\tinfowindow.open(map_map_6a048d9587e90,marker_map_6a048d9587e90);\r\n\t\t\t\t\t\t  \t});}\r\n\t\t\tcatch(e){};\r\n\t\t\tjQuery(document).ready(function($){\r\n\t\t\t\tgoogle.maps.event.trigger(map_map_6a048d9587e90, 'resize');\r\n\t\t\t\t$(window).resize(function(){\r\n\t\t\t\t\tgoogle.maps.event.trigger(map_map_6a048d9587e90, 'resize');\r\n\t\t\t\t\tif(map_map_6a048d9587e90!=null)\r\n\t\t\t\t\t\tmap_map_6a048d9587e90.setCenter(coordinate_map_6a048d9587e90);\r\n\t\t\t\t});\r\n\t\t\t\t$('.ui-tabs').bind('tabsactivate', function(event, ui) {\r\n\t\t\t\t   if($(this).find('.ultimate-map-wrapper').length > 0)\r\n\t\t\t\t\t{\r\n\t\t\t\t\t\tsetTimeout(function(){\r\n\t\t\t\t\t\t\t$(window).trigger('resize');\r\n\t\t\t\t\t\t},200);\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t\t$('.ui-accordion').bind('accordionactivate', function(event, ui) {\r\n\t\t\t\t   if($(this).find('.ultimate-map-wrapper').length > 0)\r\n\t\t\t\t\t{\r\n\t\t\t\t\t\tsetTimeout(function(){\r\n\t\t\t\t\t\t\t$(window).trigger('resize');\r\n\t\t\t\t\t\t},200);\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t\t$(window).load(function(){\r\n\t\t\t\t\tsetTimeout(function(){\r\n\t\t\t\t\t\t$(window).trigger('resize');\r\n\t\t\t\t\t},200);\r\n\t\t\t\t});\r\n\t\t\t\t$('.ult_exp_section').select(function(){\r\n\t\t\t\t\tif($(map_map_6a048d9587e90).parents('.ult_exp_section'))\r\n\t\t\t\t\t{\r\n\t\t\t\t\t\tsetTimeout(function(){\r\n\t\t\t\t\t\t\t$(window).trigger('resize');\r\n\t\t\t\t\t\t},200);\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t\t$(document).on('onUVCModalPopupOpen', function(){\r\n\t\t\t\t\tif($(map_map_6a048d9587e90).parents('.ult_modal-content'))\r\n\t\t\t\t\t{\r\n\t\t\t\t\t\tsetTimeout(function(){\r\n\t\t\t\t\t\t\t$(window).trigger('resize');\r\n\t\t\t\t\t\t},200);\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t\t$(document).on('click','.ult_tab_li',function(){\r\n\t\t\t\t\t$(window).trigger('resize');\r\n\t\t\t\t\tsetTimeout(function(){\r\n\t\t\t\t\t\t$(window).trigger('resize');\r\n\t\t\t\t\t},200);\r\n\t\t\t\t});\r\n\t\t\t});\r\n\t\t\tfunction toggleBounce() {\r\n\t\t\t  if (marker_map_6a048d9587e90.getAnimation() != null) {\r\n\t\t\t\tmarker_map_6a048d9587e90.setAnimation(null);\r\n\t\t\t  } else {\r\n\t\t\t\tmarker_map_6a048d9587e90.setAnimation(google.maps.Animation.BOUNCE);\r\n\t\t\t  }\r\n\t\t\t}\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script>[\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1485194053084{padding-top: 80px !important;padding-right: 80px !important;padding-bottom: 60px !important;padding-left: 80px !important;}&#8221; offset=&#8221;vc_col-md-6&#8243;][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<h3>Ti ascoltiamo!<\/h3>\n<p>[\/vc_column_text][vc_column_text css_animation=&#8221;none&#8221;]<\/p>\n<p style=\"color: #aaa; font-size: 14px;\">Se avete dubbi o domande, restiamo personalmente a vostra disposizione presso i nostri uffici centrali:<br \/>\nPoligono Industriale di Guarnizo, Lotto 94. 39611, Astillero. Cantabria.<br \/>\nDa Luned\u00ec a Venerd\u00ec, mattina 09-14 \/\/ pomeriggio: 17-19.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;25px&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13224-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"13224\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/12985#wpcf7-f13224-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"13224\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.5\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13224-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> <span style=\"font-size: 13px; font-weight: 900; font-family: 'Source Sans Pro'; color: #0084cf;\">Nome *<\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label><span style=\"font-size: 13px; font-weight: 900; font-family: 'Source Sans Pro'; color: #0084cf;\">E-mail *<\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> <span style=\"font-size: 13px; font-weight: 900; font-family: 'Source Sans Pro'; color: #0084cf;\">Oggetto *<\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> <span style=\"font-size: 13px; font-weight: 900; font-family: 'Source Sans Pro'; color: #0084cf;\">Messaggio *<\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"3\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p style=\"font-size: 11px; padding-bottom: 10px;\"><span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-186\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"checkbox-186[]\" value=\"\" \/><span class=\"wpcf7-list-item-label\"><\/span><\/span><\/span><\/span> Ho letto e accetto il contenuto della <a href=\"http:\/\/www.vegapas.com\/politica-proteccion-datos\" target=\"_blank\">Politica di protezione dei dati<\/a>.\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Inviare\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-vz-jquery&#8221; bg_image_new=&#8221;id^12081|url^https:\/\/vegapas.com\/wp-content\/uploads\/2016\/05\/vega_pas_banners_fondo-rrhh3.gif|caption^null|alt^null|title^vega_pas_banners_fondo-rrhh3|description^null&#8221; bg_image_size=&#8221;contain&#8221; css=&#8221;.vc_custom_1485196671081{margin-bottom: 0px !important;padding-top: 120px !important;padding-right: 10% !important;padding-bottom: 120px !important;padding-left: 10% !important;background-color: #0084cf !important;}&#8221;][vc_column css=&#8221;.vc_custom_1465835271582{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1465835342953{background-color: #ffffff !important;border-radius: 10px !important;}&#8221; el_class=&#8221;add-shadow-row&#8221;][vc_column_inner css=&#8221;.vc_custom_1485430393236{padding-top: 200px !important;padding-bottom: 200px !important;background-image: url(https:\/\/vegapas.com\/wp-content\/uploads\/2016\/05\/vegapas_rrhh7.png?id=12331) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;border-radius: 5px !important;}&#8221; offset=&#8221;vc_col-md-6&#8243;][\/vc_column_inner][vc_column_inner css=&#8221;.vc_custom_1469440759121{padding-top: 70px !important;padding-right: 60px !important;padding-bottom: 50px !important;padding-left: 60px !important;background-color: #ffffff !important;border-radius: 5px !important;}&#8221; offset=&#8221;vc_col-md-6&#8243;][vc_column_text css_animation=&#8221;bottom-to-top&#8221;]<\/p>\n<h4>Siamo fatti di te, Lavora con noi!<\/h4>\n<p>[\/vc_column_text][vc_column_text css_animation=&#8221;bottom-to-top&#8221;]Se vuoi far parte della famiglia Vega Pas, non esitare a contattarci. Cerchiamo professionisti di talento, con entusiasmo, responsabili e con voglia di crescere professionalmente con noi.[\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13225-o2\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"13225\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/12985#wpcf7-f13225-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"13225\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.5\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13225-o2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> <span style=\"font-size: 13px; font-weight: 900; font-family: 'Source Sans Pro'; color: #0084cf;\">Nome *<\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label><span style=\"font-size: 13px; font-weight: 900; font-family: 'Source Sans Pro'; color: #0084cf;\">E-mail *<\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><span style=\"font-size: 13px; font-weight: 900; font-family: 'Source Sans Pro'; color: #0084cf;\">Allegare il Curriculum vitae *<\/span>\n<\/p>\n<p style=\"line-height: 1px; font-size: 12px;\">(m\u00e1x. 10mb | pdf, jpg, doc, docx, zip)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"adjuntos\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file wpcf7-validates-as-required\" accept=\".zip,.jpg,.pdf,.doc,.docx\" aria-required=\"true\" aria-invalid=\"false\" type=\"file\" name=\"adjuntos\" \/><\/span>\n<\/p>\n<p style=\"font-size: 11px; padding-bottom: 10px;\"><span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-186\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"checkbox-186[]\" value=\"\" \/><span class=\"wpcf7-list-item-label\"><\/span><\/span><\/span><\/span> Ho letto e accetto il contenuto della <a href=\"http:\/\/www.vegapas.com\/politica-proteccion-datos\" target=\"_blank\">Politica di protezione dei dati<\/a>.\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Inviare\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1484763304283{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1484763433678{margin-top: 0px !important;padding-top: 0px !important;}&#8221;]<div class=\" vc_custom_1485197278125 ubtn-ctn-center \"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-center ubtn-block \" href = \"https:\/\/www.facebook.com\/vegapas\/\" target=' _blank' ><button type=\"button\" id=\"ubtn-4312\" class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-block ubtn-no-hover-bg  none  ubtn-sep-icon ubtn-sep-icon-left-push  ubtn-center   tooltip-6a048d95a08a7 ubtn-block\"  data-hover=\"#ffffff\" data-border-color=\"#006bc0\" data-bg=\"#006bc0\" data-hover-bg=\"#006bc0\" data-border-hover=\"#006bc0\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-4312'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:bold;border-radius:0px;border-width:30px;border-color:#006bc0;border-style:solid;background: #006bc0;color: #ffffff;\"><span class=\"ubtn-data ubtn-icon\"><i class=\"Defaults-facebook facebook-f\" style=\"font-size:32px;color:#ffffff;\"><\/i><\/span><span class=\"ubtn-hover\" style=\"background-color:#006bc0\"><\/span><span class=\"ubtn-data ubtn-text \" >FACEBOOK<\/span><\/button><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1484763443308{margin-top: 0px !important;padding-top: 0px !important;}&#8221;]<div class=\" vc_custom_1485271927677 ubtn-ctn-center \"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-center ubtn-block \" href = \"https:\/\/www.flickr.com\/photos\/126603693@N07\/\" target=' _blank' ><button type=\"button\" id=\"ubtn-3597\" class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-block ubtn-no-hover-bg  none  ubtn-sep-icon ubtn-sep-icon-left-push  ubtn-center   tooltip-6a048d95a097c ubtn-block\"  data-hover=\"#ffffff\" data-border-color=\"#ec6d10\" data-bg=\"#ec6d10\" data-hover-bg=\"#ec6d10\" data-border-hover=\"#ec6d10\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-3597'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:bold;border-radius:0px;border-width:30px;border-color:#ec6d10;border-style:solid;background: #ec6d10;color: #ffffff;\"><span class=\"ubtn-data ubtn-icon\"><i class=\"Defaults-flickr\" style=\"font-size:32px;color:#ffffff;\"><\/i><\/span><span class=\"ubtn-hover\" style=\"background-color:#ec6d10\"><\/span><span class=\"ubtn-data ubtn-text \" >FLICKR<\/span><\/button><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1484763452174{margin-top: 0px !important;padding-top: 0px !important;}&#8221;]<div class=\" vc_custom_1485271910723 ubtn-ctn-center \"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-center ubtn-block \" href = \"https:\/\/www.linkedin.com\/company-beta\/5266004\/\" target=' _blank' ><button type=\"button\" id=\"ubtn-8892\" class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-block ubtn-no-hover-bg  none  ubtn-sep-icon ubtn-sep-icon-left-push  ubtn-center   tooltip-6a048d95a09c1 ubtn-block\"  data-hover=\"#ffffff\" data-border-color=\"#ffce3c\" data-bg=\"#ffce3c\" data-hover-bg=\"#ffce3c\" data-border-hover=\"#ffce3c\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-8892'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:bold;border-radius:0px;border-width:30px;border-color:#ffce3c;border-style:solid;background: #ffce3c;color: #ffffff;\"><span class=\"ubtn-data ubtn-icon\"><i class=\"Defaults-linkedin\" style=\"font-size:32px;color:#ffffff;\"><\/i><\/span><span class=\"ubtn-hover\" style=\"background-color:#ffce3c\"><\/span><span class=\"ubtn-data ubtn-text \" >LINKEDIN<\/span><\/button><\/a><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; gap=&#8221;30&#8243; css=&#8221;.vc_custom_1484739459996{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 30px !important;padding-bottom: 30px !important;background-color: #0084cf !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1487673180106{margin-bottom: 12px !important;}&#8221;] Telefono: [\/vc_column_text][vc_column_text css_animation=&#8221;none&#8221;] +34 942 559 841 [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1484811173131{margin-bottom:&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12985","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contatto - VEGA PAS<\/title>\n<meta name=\"description\" content=\"Vega Pas. Especialistas en la elaboraci\u00f3n y distribuci\u00f3n, a nivel nacional, de productos relacionados con la panader\u00eda y boller\u00eda, conservando una receta tradicional y cuidando la calidad de sus ingredientes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vegapas.com\/it\/contatto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contatto - VEGA PAS\" \/>\n<meta property=\"og:description\" content=\"Vega Pas. Especialistas en la elaboraci\u00f3n y distribuci\u00f3n, a nivel nacional, de productos relacionados con la panader\u00eda y boller\u00eda, conservando una receta tradicional y cuidando la calidad de sus ingredientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vegapas.com\/it\/contatto\/\" \/>\n<meta property=\"og:site_name\" content=\"VEGA PAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vegapas\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-21T10:40:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vegapas.com\/it\/contatto\/\",\"url\":\"https:\/\/vegapas.com\/it\/contatto\/\",\"name\":\"Contatto - VEGA PAS\",\"isPartOf\":{\"@id\":\"https:\/\/vegapas.com\/#website\"},\"datePublished\":\"2016-05-04T12:25:53+00:00\",\"dateModified\":\"2017-02-21T10:40:33+00:00\",\"description\":\"Vega Pas. Especialistas en la elaboraci\u00f3n y distribuci\u00f3n, a nivel nacional, de productos relacionados con la panader\u00eda y boller\u00eda, conservando una receta tradicional y cuidando la calidad de sus ingredientes.\",\"breadcrumb\":{\"@id\":\"https:\/\/vegapas.com\/it\/contatto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vegapas.com\/it\/contatto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vegapas.com\/it\/contatto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/vegapas.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contatto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vegapas.com\/#website\",\"url\":\"https:\/\/vegapas.com\/\",\"name\":\"VEGA PAS\",\"description\":\"Productos pasiegos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vegapas.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contatto - VEGA PAS","description":"Vega Pas. Especialistas en la elaboraci\u00f3n y distribuci\u00f3n, a nivel nacional, de productos relacionados con la panader\u00eda y boller\u00eda, conservando una receta tradicional y cuidando la calidad de sus ingredientes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vegapas.com\/it\/contatto\/","og_locale":"it_IT","og_type":"article","og_title":"Contatto - VEGA PAS","og_description":"Vega Pas. Especialistas en la elaboraci\u00f3n y distribuci\u00f3n, a nivel nacional, de productos relacionados con la panader\u00eda y boller\u00eda, conservando una receta tradicional y cuidando la calidad de sus ingredientes.","og_url":"https:\/\/vegapas.com\/it\/contatto\/","og_site_name":"VEGA PAS","article_publisher":"https:\/\/www.facebook.com\/vegapas","article_modified_time":"2017-02-21T10:40:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vegapas.com\/it\/contatto\/","url":"https:\/\/vegapas.com\/it\/contatto\/","name":"Contatto - VEGA PAS","isPartOf":{"@id":"https:\/\/vegapas.com\/#website"},"datePublished":"2016-05-04T12:25:53+00:00","dateModified":"2017-02-21T10:40:33+00:00","description":"Vega Pas. Especialistas en la elaboraci\u00f3n y distribuci\u00f3n, a nivel nacional, de productos relacionados con la panader\u00eda y boller\u00eda, conservando una receta tradicional y cuidando la calidad de sus ingredientes.","breadcrumb":{"@id":"https:\/\/vegapas.com\/it\/contatto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vegapas.com\/it\/contatto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vegapas.com\/it\/contatto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vegapas.com\/it\/"},{"@type":"ListItem","position":2,"name":"Contatto"}]},{"@type":"WebSite","@id":"https:\/\/vegapas.com\/#website","url":"https:\/\/vegapas.com\/","name":"VEGA PAS","description":"Productos pasiegos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vegapas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/vegapas.com\/it\/wp-json\/wp\/v2\/pages\/12985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vegapas.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vegapas.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vegapas.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vegapas.com\/it\/wp-json\/wp\/v2\/comments?post=12985"}],"version-history":[{"count":0,"href":"https:\/\/vegapas.com\/it\/wp-json\/wp\/v2\/pages\/12985\/revisions"}],"wp:attachment":[{"href":"https:\/\/vegapas.com\/it\/wp-json\/wp\/v2\/media?parent=12985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}